{"id":4188,"date":"2013-01-23T15:12:42","date_gmt":"2013-01-23T15:12:42","guid":{"rendered":"http:\/\/martha.org.mx\/una-politica-con-causa\/?p=4188"},"modified":"2019-08-07T20:31:43","modified_gmt":"2019-08-07T20:31:43","slug":"suenos-sobre-ruedas","status":"publish","type":"post","link":"https:\/\/martha.org.mx\/una-politica-con-causa\/suenos-sobre-ruedas\/","title":{"rendered":"Sue\u00f1os Sobre Ruedas"},"content":{"rendered":"\n<p><a href=\"http:\/\/martha.org.mx\/informacion-general\/SuenoSobreRuedas.pdf\">MEMORIA GR\u00c1FICA<\/a> DE LA BICICLETA EN LA CIUDAD DE M\u00c9XICO (2006 &#8211; 2012)  <\/p>\n\n\n\n<p>Seis a\u00f1os han transcurrido desde que decidimos emprender un nuevo camino, uno cuya principal meta es promover una movilidad alternativa y fomentar el uso de la bicicleta en la Ciudad de M\u00e9xico.  <\/p>\n\n\n\n<p>En este tiempo compartimos sue\u00f1os y andares con millones de personas que buscan promover espacios para propiciar una forma de movilidad activa, as\u00ed como el rescate de los espacios p\u00fablicos a favor de los ciudadanos y la integraci\u00f3n de la bicicleta como un nuevo y principal actor de la vida urbana.  <\/p>\n\n\n\n<p>Con Sue\u00f1os sobre ruedas, memoria gr\u00e1fica de la bicicleta en la Ciudad de M\u00e9xico (2006 &#8211; 2012), queremos hacer un recuento de los avances y logros de la intenci\u00f3n de transformar los h\u00e1bitos de movilidad en la ciudad, as\u00ed como plantear los retos que el futuro seguramente traer\u00e1 consigo. <\/p>\n\n\n\n<p>Hoy, muchos de los proyectos que se implementaron de la Estrategia de Movilidad en Bicicleta, son semillas cuyo \u00e9xito se traduce en perdurabilidad. Mu\u00e9vete en Bici logr\u00f3 abrir un nuevo panorama sobre otras formas de convivencia, el Sistema de Transporte Individual Ecobici sent\u00f3 las bases para mejorar la movilidad en la ciudad, y los proyectos de infraestructura y educaci\u00f3n vial fueron otro importante eslab\u00f3n en la b\u00fasqueda de hacer accesible el uso de la bicicleta a la ciudadan\u00eda.  So\u00f1amos sobre dos ruedas y hoy rodamos sobre los primeros senderos de un largo camino por delante. <\/p>\n\n\n\n<p>Nuestro destino es lograr, todos juntos, que la Ciudad de M\u00e9xico contin\u00fae siendo un ejemplo de un cambio positivo a favor de la movilidad sustentable en el mundo. <\/p>\n\n\n\n<p>Martha Delgado Peralta<\/p>\n\n\n\n<p>Secretaria del Medio Ambiente del Gobierno del Distrito Federal <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Memoria gr\u00e1fica de la bici en el DF<\/p>\n","protected":false},"author":1,"featured_media":5767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-4188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-secretaria"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/4188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/comments?post=4188"}],"version-history":[{"count":3,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/4188\/revisions"}],"predecessor-version":[{"id":5768,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/4188\/revisions\/5768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media\/5767"}],"wp:attachment":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media?parent=4188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/categories?post=4188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/tags?post=4188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}