{"id":3403,"date":"2012-07-31T10:14:23","date_gmt":"2012-07-31T10:14:23","guid":{"rendered":"http:\/\/martha.org.mx\/una-politica-con-causa\/?p=3403"},"modified":"2019-07-03T18:26:14","modified_gmt":"2019-07-03T18:26:14","slug":"descalza-y-mojada","status":"publish","type":"post","link":"https:\/\/martha.org.mx\/una-politica-con-causa\/descalza-y-mojada\/","title":{"rendered":"Relatos de Fogata"},"content":{"rendered":"<p>Recomiendo much\u00edsimo una compilaci\u00f3n de relatos llamada &#8220;Relatos de Fogata&#8221;. Es una compilaci\u00f3n reci\u00e9n publicada por la CONANP, editada por los bi\u00f3logos Ignacio March Mifsut y Marco A. Lazcano Barrero. A trav\u00e9s de diversos relatos peque\u00f1os y entretenidos, se puede uno acercar a la Naturaleza a trav\u00e9s de la mirada de los m\u00e1s diversos amantes a la Naturaleza. Aqu\u00ed te comparto mi aportaci\u00f3n a esta publicaci\u00f3n. El libro consta de 89 relatos divididos en cinco partes: 1. Encuentros cercanos con seres de la naturaleza, 2. Recuerdos de campo, 3. En situaciones cr\u00edticas, 4. Vivencias con habitantes locales y 5. Sucesos sobrenaturales. Para leer m\u00e1s relatos puedes acceder directamente a la publicaci\u00f3n gratuita <a href=\"http:\/\/difusion.conanp.gob.mx\/relatos_de_fogata_low.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">haciendo click aqu\u00ed<\/a>. Mientras tanto, te comparto aqu\u00ed mi propio relato:<\/p>\n<p><strong>&#8220;Descalza y mojada&#8221; <\/strong><\/p>\n<p>Quiso mi suerte que desde muy temprano, mi vida se encajara en el para\u00edso mexicano llamado \u201cBah\u00eda San Carlos\u201d, hermoso recodo en el Mar de Cort\u00e9s donde por fortuna mis padres tuvieron que enclavar nuestra estancia familiar. Yo siempre digo que all\u00ed nac\u00ed porque fue precisamente all\u00ed donde despert\u00e9 a la vida y a la naturaleza. Tendr\u00eda por entonces seis a\u00f1os, y crec\u00ed al estilo salvaje a orillas del mar. No podr\u00eda haberme pasado nada mejor, especialmente porque apenas iniciaba mi vida. Tengo una hermana gemela que por desgracia no sigui\u00f3 sus pasos junto a los m\u00edos. Ella era recatada, asustadiza y responsable de sus actos, y nunca quiso seguirme en mis \u201cinvestigaciones\u201d, de modo que me lanc\u00e9 por mi cuenta, teniendo que esconderme de ella pues tambi\u00e9n era chismosa.<\/p>\n<p><img decoding=\"async\" class=\"alignright\" src=\"http:\/\/farm1.static.flickr.com\/23\/30303184_16a7abaffe.jpg\" alt=\"\" width=\"30%\">Afortunadamente tuve una madre muy comprensiva, que me dio toda la libertad que yo necesitaba para averiguar por aqu\u00ed y por all\u00e1 sin que se muriera de miedo. Cuando tuvo que sacarme del mar, aquella vez que decid\u00ed traer el desayuno a casa y me hice de una cubeta y un palo de ca\u00f1a bien afilado, y me lanc\u00e9 un poco mar adentro, donde sab\u00eda que se encontraban esos peque\u00f1os monstruos, pues ya me hab\u00edan mordido el dedo gordo del pie derecho. Fue la primera vez que la vi nerviosa y angustiada por mi osad\u00eda, y muy sorprendida cuando puse sobre la mesa de la terraza aquella cubeta repleta de jaibas y cangrejos que, por supuesto, ya ni se mov\u00edan porque yo los hab\u00eda atravesado con mi improvisada pero mortal arma. Despu\u00e9s del rega\u00f1o, las dos nos pusimos a limpiarlas para cocerlas y comerlas alegremente, ba\u00f1adas en jugo de lim\u00f3n. Yo creo que esa vez supo mi madre de mi autosuficiencia, y tal vez respir\u00f3 aliviada al darse cuenta tambi\u00e9n de que no tendr\u00eda que seguirme los rastros todo el d\u00eda, como a mis hermanas. Y ten\u00eda raz\u00f3n: yo olfate\u00e9 que ellas me necesitaban, pero mis planes eran otros: \u00a1necesitaba libertad! Que ellas se las arreglaran como pudieran y quisieran, haciendo dibujitos, brincando la reata o lo que fuera. Yo estaba dentro de otro contexto. Y as\u00ed, mis hermanitas que tanto se cuidaban tuvieron muchos m\u00e1s accidentes que yo a la deriva.<\/p>\n<p>Una ma\u00f1ana me sub\u00ed a los riscos bastante alejados de casa, desde donde pod\u00eda ver la playa en que se encontraban alineadas todas las casas, grandes y chicas, y entre ellas la m\u00eda. La mayor\u00eda eran de gringos que disfrutaban de nuestro hermoso entorno mexicano. Oteando hacia lo lejos me di cuenta de que se pod\u00eda bajar por el otro lado de aquellos riscos. Tras ellos, el hermoso e imponente \u201cTetakawi\u201d (Monta\u00f1a llamada literalmente \u201cTetas de Cabra\u201d, por su silueta) se alzaba como vigilante de sus hermosos para\u00edsos. Iba yo descalza, con mis chanclas playeras metidas en mi cubeta en una mano, y mi larga lanza de ca\u00f1a en la otra, la cual no abandonaba nunca porque era mi apoyo y a veces mi arma. De las piedras de esos riscos, sal\u00edan animales extra\u00f1os que no s\u00e9 por qu\u00e9 no se asustaban con mi presencia, como yo tampoco de la de ellos. No los mataba, porque tampoco ten\u00eda yo coraz\u00f3n malvado y comprend\u00eda que esa era su casa que yo respetaba. Del otro lado, bajando con cuidado, hab\u00eda una peque\u00f1a playita adonde no azotaban las olas, sino que llegaban con cari\u00f1o, s\u00f3lo acariciando la arena. Decid\u00ed que ese ser\u00eda mi lugar. Una vez que me encontr\u00e9 abajo, tom\u00e9 posesi\u00f3n de la peque\u00f1a cuevita como mi lugar secreto. Tan secreto y confiable que decid\u00ed guardar all\u00ed mis implementos de exploraci\u00f3n.<\/p>\n<p><img decoding=\"async\" class=\"alignright\" src=\"http:\/\/4.bp.blogspot.com\/-69M87pZJqes\/TjTAh65ElcI\/AAAAAAAAAGk\/UXM4EJunYBI\/s640\/Tetakawi+al+atardecer+LR+.jpg\" alt=\"\" width=\"40%\">Me sent\u00e9 sobre unas piedras planas y mi vista huy\u00f3 hacia el infinito, donde una raya marcaba, como una hendidura, los l\u00edmites entre mar y cielo. Por ah\u00ed se met\u00eda el sol en cierta \u00e9poca del a\u00f1o. San Carlos tiene una peque\u00f1a cordillera que se ilumina con todos los rojos posibles a esta hora. Pero para ver esa maravilla, ten\u00eda que darle la vuelta al Tetakawi por casi la mitad de sus faldas. O ve\u00eda yo la puesta del sol, o ve\u00eda yo la iluminaci\u00f3n sobre los cerros. Era cuesti\u00f3n de escoger. Al fin y al cabo todo eso era m\u00edo. Los olores marinos penetraron por mi nariz hasta abotagar mis sentidos. Eran oleadas de frescura, de humedad, de calor vivificante. Cerr\u00e9 los ojos y me llen\u00e9 de vida. Aprend\u00ed c\u00f3mo, al igual que un beb\u00e9 acompasa su coraz\u00f3n al de su madre, una ni\u00f1a puede acompasar su respiraci\u00f3n con el oleaje marino. \u00a1Eso era hermoso! De aqu\u00ed en adelante lo har\u00eda todas las noches.<\/p>\n<p><a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/07\/medusa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3424\" title=\"medusa\" src=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/07\/medusa-176x300.jpg\" alt=\"\" width=\"176\" height=\"300\" srcset=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/07\/medusa-176x300.jpg 176w, https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/07\/medusa.jpg 179w\" sizes=\"auto, (max-width: 176px) 100vw, 176px\" \/><\/a>Cuando abr\u00ed los ojos, un gran lote de algas marinas hab\u00eda subido con el oleaje hasta mi playita, quedando all\u00ed expuesto a mi inspecci\u00f3n. Baj\u00e9 r\u00e1pidamente el escaso tramo que me separaba de ellas. Tom\u00e9 mi vara y comenc\u00e9 a picotear, y grande fue mi susto cuando una bola transparente salt\u00f3 cayendo casi sobre mi pi\u00e9. No me arredr\u00e9. La ensart\u00e9 sin piedad en mi varilla y la alej\u00e9 de m\u00ed, dej\u00e1ndola palpitante en la arena, pero a todas luces muerta. Mi instinto me dijo que era algo muy malo. Regres\u00e9 a mis algas y recobr\u00e9 mi alegr\u00eda al encontrar dentro de ese revoltijo peque\u00f1os pececitos que se hab\u00edan enredado, y tambi\u00e9n caracoles muy hermosos. Liber\u00e9 con cuidado a los peces y los devolv\u00ed al mar donde, estaba segura, dar\u00edan brincos de alegr\u00eda por haberse salvado de la muerte. Los caracoles no corrieron con la misma suerte, pues aparte de estar cubiertos con hermosas conchas retorcidas, tra\u00edan dentro \u201cbocattos di cardinali\u201d. Decid\u00ed llev\u00e1rselos a mi mam\u00e1 para contentarla esa noche. Eran lo suficientemente grandes como para completar una cena familiar. Observ\u00e9 con amor la puesta del sol, y me dispuse a regresar a casa.<\/p>\n<p>Esa tarde hab\u00eda yo encontrado mi maravillosa cueva, hab\u00eda respirado al comp\u00e1s del mar, y llevaba en mi cubeta un tesoro para la cena. Hab\u00eda descubierto caminitos, subidas, bajadas, y tambi\u00e9n recib\u00ed una lecci\u00f3n para no ser tan cr\u00e9dula y en adelante, cuidarme de lo que podr\u00eda hacerme da\u00f1o. Vivir en la naturaleza no es rom\u00e1ntico como algunos piensan: la tranquilidad, la hermosura de las vistas, la pureza del estado salvaje de la vida, se ven inmersas en una lucha por la sobrevivencia. Yo ni\u00f1a en la naturaleza era un ser m\u00e1s que se defend\u00eda del entorno, pero tambi\u00e9n era parte intr\u00ednseca de \u00e9l. Por las noches, despu\u00e9s que mi mam\u00e1 nos dejaba en nuestro cuarto \u201cdurmiendo\u201d, yo me volv\u00eda a poner mi traje de ba\u00f1o (del que creo no me desprend\u00ed en a\u00f1os) y bajaba hasta la terraza que ten\u00eda una peque\u00f1a escalerita hacia la playa.<\/p>\n<p>Me sentaba yo all\u00ed, d\u00e1ndome cuenta de qu\u00e9 manera la oscuridad del mar puede ser misteriosa, pero tambi\u00e9n es el gran manto conocido que te cubre como tu casa. Caminaba un peque\u00f1o trecho sin alejarme demasiado, y tuve mis experiencias fuertes: una noche me encontr\u00e9 con un delf\u00edn muerto. Otra, que recuerdo con horror, baj\u00f3 volando un pel\u00edcano haciendo mucho esc\u00e1ndalo con sus alerones, y se par\u00f3 a un metro m\u00edo abriendo el pico como si quisiera comerme\u2026 confieso que tuve que correr de vuelta a casa.<\/p>\n<p><img decoding=\"async\" class=\"alignright\" src=\"http:\/\/www.enelmar.es\/wp-content\/uploads\/2010\/12\/Erizo-cachero-Arbacia-lixula-Muelle-de-Garachico-IMG_2540.jpg\" alt=\"\" width=\"30%\">Y hay otra peripecia que no puedo olvidar, y ya ver\u00e1n porqu\u00e9: Me met\u00ed al mar una tarde s\u00f3lo para nadar, y las olas estaban enojadas. Me arrastraron hasta los riscos y me golpe\u00e9 contra ellos. El resultado fue que los erizos me esperaban y sal\u00ed de all\u00ed con codos y rodillas cubiertos de p\u00faas, que ni mi mam\u00e1 pod\u00eda quitarme sin que yo gritara como loca de dolor. Pas\u00e9 una semana expulsando p\u00faas y maldiciendo el haberme descuidado. Otra lecci\u00f3n. Mi pap\u00e1 nos regal\u00f3 bicicletas, y fue entonces cuando yo pude irme a explorar realmente lejos. Armada con todos mis pertrechos me fui a una playa lejana que se llama \u201cAlgodones\u201d. Un poco m\u00e1s all\u00e1, descubr\u00ed un p\u00e1ramo arenoso, lleno de dunas y decenas de sahuaros enormes que ten\u00edan agujeros en sus anchos brazos que serv\u00edan de nido a las aves. Aquello fue tan incre\u00edble que tuve que contarle a mis pap\u00e1s e insistirles que nos llevaran a toda la familia para que vieran aquel impactante espect\u00e1culo. Pero por supuesto, mis padres quisieron saber c\u00f3mo hab\u00eda llegado hasta all\u00e1 para descubrir aquello. Tuve que confesar \u201cparte\u201d de mis actividades y por supuesto, vino algo que no esperaba: un fuerte castigo, pero no sirvi\u00f3 de nada.<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" src=\"http:\/\/2.bp.blogspot.com\/_3EuPj0S9r34\/SL88iLJQrvI\/AAAAAAAAJs0\/FY2Rp3mU2Fk\/s400\/dunas-algodones.jpg\" alt=\"\" width=\"40%\">Hace poco tuve oportunidad de ir a San Carlos, y mi coraz\u00f3n se llen\u00f3 de recuerdos. Aunque sigue siendo un para\u00edso, San Carlos no ha sido la excepci\u00f3n de la expansi\u00f3n urbana. Sigue siendo un peque\u00f1o pueblo, pero el Estero del Soldado y muchas playas que eran v\u00edrgenes est\u00e1n rodeados de construcciones. San Carlos ya no es el mismo, mas tengo que admitir que yo tampoco. A pesar de que los veranos pod\u00edamos llegar a 50 grados cent\u00edgrados, no recuerdo jam\u00e1s haber tenido calor cuando era ni\u00f1a. \u00a1Ahora ser\u00eda imposible obviar que en esa \u00e9poca es un infierno! Mi gran aventura fue vivir la ni\u00f1ez descalza y mojada. Subida en los \u00e1rboles para esconderme del resto de los ni\u00f1os. Sufr\u00ed picadura de mantaraya, quemadura de aguamala, pellizco de jaiba, ensartamiento de erizo. M\u00e1s que encontrarme con la naturaleza, crec\u00ed en ella, y me desencontr\u00e9 con el mundo cuando sal\u00ed de ella. Aunque tal vez no todo sea tan malo. San Carlos sigue estando all\u00ed y estoy segura de que cada vez que regrese, los recuerdos volver\u00e1n a m\u00ed haci\u00e9ndome nuevamente feliz tan solo por saber que fui una ni\u00f1a descalza y mojada, en busca de todo lo que encontr\u00e9, que no compart\u00ed con nadie, porque nadie ten\u00eda como yo la ansiedad de meterse en la naturaleza a riesgo de lo que fuera, y que eso que encontr\u00e9 me marc\u00f3 para siempre en mi vida adulta que ha seguido igual, en busca de los inimaginables tesoros que nos brinda la tierra, am\u00e1ndola y respet\u00e1ndola.<\/p>\n<p><a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/07\/playa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-3429\" title=\"playa\" src=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/07\/playa-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/07\/playa-300x225.jpg 300w, https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/07\/playa.jpg 604w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div style=\"clear: both;\">&nbsp;<\/div>\n<p><a href=\"http:\/\/difusion.conanp.gob.mx\/relatos_de_fogata_low.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Haz click aqu\u00ed para acceder a m\u00e1s &#8220;Relatos de Fogata&#8221;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un acercamiento a la Naturaleza<\/p>\n","protected":false},"author":1,"featured_media":4754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[90,14,58],"tags":[],"class_list":["post-3403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-escritos-por-martha-delgado","category-educacion-ambiental","category-educacion-ambiental-martha"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/3403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/comments?post=3403"}],"version-history":[{"count":35,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/3403\/revisions"}],"predecessor-version":[{"id":4755,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/3403\/revisions\/4755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media\/4754"}],"wp:attachment":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media?parent=3403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/categories?post=3403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/tags?post=3403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}