{"id":2658,"date":"2012-05-24T10:39:03","date_gmt":"2012-05-24T10:39:03","guid":{"rendered":"http:\/\/martha.org.mx\/una-politica-con-causa\/?p=2658"},"modified":"2019-08-12T22:33:54","modified_gmt":"2019-08-12T22:33:54","slug":"aneas","status":"publish","type":"post","link":"https:\/\/martha.org.mx\/una-politica-con-causa\/aneas\/","title":{"rendered":"ANEAS"},"content":{"rendered":"\n<p>La <a href=\"http:\/\/aneas.com.mx\/quienes-somos\/\">Asociaci\u00f3n Nacional de Empresas de Agua y Saneamiento de M\u00e9xico A.C. (ANEAS) <\/a>con m\u00e1s de 35 a\u00f1os de experiencia, agrupa a Organismos Operadores de Agua Potable del pa\u00eds, cuyo objetivo b\u00e1sico es apoyar la elevaci\u00f3n de la eficiencia en la prestaci\u00f3n de los servicios as\u00ed como fomentar el  nivel de profesionalizaci\u00f3n y autonom\u00eda del capital humano.<\/p>\n\n\n\n<p>Fue creada como EAS el 3 de abril de 1992 como resultado del primer encuentro de grandes e importantes Organismos de Agua Potable y Saneamiento, celebrado en la ciudad de Canc\u00fan, Quintana Roo, cuyo objetivo principal fue el an\u00e1lisis de la problem\u00e1tica del Agua y el Saneamiento, y cambi\u00f3 su nombre a Asociaci\u00f3n Nacional de Empresas de Agua y Saneamiento en febrero de 1998.<\/p>\n\n\n\n<p>Empresas de Agua y Saneamiento de M\u00e9xico A.C. (EAS), se cre\u00f3 a partir de la Asociaci\u00f3n Nacional de Organismos de Agua Potable y Alcantarillado (ANOAPA) para promover los cambios de la gesti\u00f3n de los Organismos Operadores de Agua Potable del pa\u00eds propiciando su transformaci\u00f3n de entes gubernamentales a verdaderas empresas p\u00fablicas y privadas.<\/p>\n\n\n\n<p>La ANEAS es una asociaci\u00f3n civil sin fines de lucro, integrada por sistemas de agua estatales y municipales de M\u00e9xico, as\u00ed como empresas privadas e instancias acad\u00e9micas y gremiales que participan en el sector; quienes aportan e intercambian conocimientos y experiencias para el logro de objetivos  particulares y colectivos.<\/p>\n\n\n\n<p>Brindamos asesor\u00eda jur\u00eddica, legislativa y fiscal, servicios para el desarrollo de capacidades y certificaci\u00f3n, apoyo t\u00e9cnico  para mejorar la operaci\u00f3n y el mantenimiento de los sistemas de agua potable, representaci\u00f3n ante autoridades y gestiones diversas, enlace con organizaciones nacionales e internacionales para compartir una gran variedad de experiencias y conocimiento; as\u00ed como organizaci\u00f3n de talleres, cursos, seminarios y eventos en M\u00e9xico y en otras latitudes.<\/p>\n\n\n\n<p>Est\u00e1 estructurada por los siguientes \u00f3rganos:<\/p>\n\n\n\n<p>La Asamblea General de Asociados<br>\nEl Consejo Directivo.<br>\nLas delegaciones regionales.<br>\nEl Director General.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empresas de Agua y Saneamiento de M\u00e9xico<\/p>\n","protected":false},"author":1,"featured_media":2659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agua"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/comments?post=2658"}],"version-history":[{"count":4,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2658\/revisions"}],"predecessor-version":[{"id":5911,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2658\/revisions\/5911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media\/2659"}],"wp:attachment":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media?parent=2658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/categories?post=2658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/tags?post=2658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}