{"id":2645,"date":"2012-05-24T10:27:51","date_gmt":"2012-05-24T10:27:51","guid":{"rendered":"http:\/\/martha.org.mx\/una-politica-con-causa\/?p=2645"},"modified":"2019-08-12T22:37:34","modified_gmt":"2019-08-12T22:37:34","slug":"archivo-historico-del-agua","status":"publish","type":"post","link":"https:\/\/martha.org.mx\/una-politica-con-causa\/archivo-historico-del-agua\/","title":{"rendered":"Archivo Hist\u00f3rico del Agua"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Archivo Hist\u00f3rico y Biblioteca Central del Agua<\/h1>\n\n\n\n<p>La Comisi\u00f3n Nacional del Agua (CONAGUA) por conducto de la Subdirecci\u00f3n General de Planeaci\u00f3n tiene bajo su administraci\u00f3n el <a href=\"https:\/\/www.gob.mx\/conagua\/acciones-y-programas\/archivo-historico-y-biblioteca-central-del-agua-149838\">Archivo Hist\u00f3rico y la Biblioteca Central del Agua.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.gob.mx\/cms\/uploads\/action_program\/main_image\/18948\/post_AHA01.jpg\" alt=\"Archivo Hist\u00f3rico y Biblioteca Central del Agua\nBalderas No. 94, Col. Centro de la Ciudad de M\u00e9xico, Cuauht\u00e9moc, C.P. 06040.\"\/><\/figure>\n\n\n\n<p>Archivo Hist\u00f3rico y Biblioteca Central del Agua Balderas No. 94, Col. Centro de la Ciudad de M\u00e9xico, Cuauht\u00e9moc, C.P. 06040.AutorComisi\u00f3n Nacional del AguaFecha de publicaci\u00f3n05 de marzo de 2018<\/p>\n\n\n\n<p>Ambos acervos resguardan gran parte de la memoria institucional que da testimonio de la experiencia del gobierno federal en el manejo del recurso h\u00eddrico, as\u00ed como de los trabajos realizados en el pa\u00eds por destacados profesionales y especialistas de diversas disciplinas en torno al agua.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El&nbsp;<strong>Archivo Hist\u00f3rico del Agua<\/strong>&nbsp;fue creado en 1994 y est\u00e1 integrado por m\u00e1s de 240 mil expedientes clasificados y organizados en siete fondos documentales con una temporalidad de 1558 a 1990.<\/li><li>El acervo de la&nbsp;<strong>Biblioteca Central del Agua&nbsp;<\/strong>se integr\u00f3 en 1986 con documentos de la Direcci\u00f3n y Subdirecci\u00f3n de Agrolog\u00eda de la extinta SRH y SARH y est\u00e1 conformada por Estudios y Proyectos generados desde la Comisi\u00f3n Nacional de Irrigaci\u00f3n hasta la actual Comisi\u00f3n Nacional del Agua. En 1994 se integran materiales bibliogr\u00e1ficos con temas sociales, econ\u00f3micos y culturales que permiten apoyar el desarrollo de la investigaci\u00f3n, la docencia y el estudio de ramas afines. El acervo resguarda m\u00e1s de 30 mil referencias, clasificadas en seis colecciones, con una temporalidad que data desde 1871 a la fecha.<\/li><\/ul>\n\n\n\n<p><strong>Procedencia institucional de los documentos<\/strong><\/p>\n\n\n\n<p>El origen documental contenido en el acervo del Archivo Hist\u00f3rico y la Biblioteca Central del Agua, se obtuvo mediante acciones de rescate y donaciones. La mayor parte de la informaci\u00f3n fue generada por las instituciones que precedieron a la CONAGUA en la administraci\u00f3n del recurso h\u00eddrico:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Secretar\u00eda de Fomento (1891-1917).<\/li><li>Secretar\u00eda de Agricultura y Fomento (1917-1946) a trav\u00e9s de la Direcci\u00f3n de Aguas, Tierras y Colonizaci\u00f3n (1917-1925).<\/li><li>Comisi\u00f3n Nacional de Irrigaci\u00f3n (CNI) (1926-1946). &nbsp;<\/li><li>Secretar\u00eda de Recursos Hidr\u00e1ulicos (1947- 1976).<\/li><li>Secretar\u00eda de Agricultura y Recursos Hidr\u00e1ulicos (1977-1989).<\/li><li>Comisi\u00f3n Nacional del Agua (CONAGUA, 16 de enero de 1989 a la fecha).<\/li><\/ul>\n\n\n\n<p><strong><em>UNESCO reconoce el valor excepcional de documentos hist\u00f3ricos sobre el agua en M\u00e9xico. Consulta el comunicado de prensa&nbsp;<a href=\"https:\/\/www.gob.mx\/conagua\/es\/prensa\/unesco-reconoce-el-valor-excepcional-de-documentos-historicos-sobre-el-agua-en-mexico?idiom=es\">aqu\u00ed.<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestra herencia hist\u00f3rica en el tema&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agua"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/comments?post=2645"}],"version-history":[{"count":3,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2645\/revisions"}],"predecessor-version":[{"id":5916,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2645\/revisions\/5916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media\/2646"}],"wp:attachment":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media?parent=2645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/categories?post=2645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/tags?post=2645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}