{"id":2119,"date":"2012-04-24T17:39:26","date_gmt":"2012-04-24T17:39:26","guid":{"rendered":"http:\/\/martha.org.mx\/una-politica-con-causa\/?p=2119"},"modified":"2019-08-13T19:14:31","modified_gmt":"2019-08-13T19:14:31","slug":"alimentacion-sin-transgenicos","status":"publish","type":"post","link":"https:\/\/martha.org.mx\/una-politica-con-causa\/alimentacion-sin-transgenicos\/","title":{"rendered":"Primera feria por una alimentaci\u00f3n libre de transg\u00e9nicos"},"content":{"rendered":"<p>Primera feria por una alimentaci\u00f3n libre de transg\u00e9nicos, 8 de abril de 2006, Parque M\u00e9xico, Hip\u00f3dromo Condesa.<\/p>\n<p>El pasado s\u00e1bado 8 de abril de 2006 se celebr\u00f3 la Primera Feria por una Alimentaci\u00f3n libre de Transg\u00e9nicos, en el Parque M\u00e9xico de la colonia Hip\u00f3dromo en la ciudad de M\u00e9xico, en el marco de la Jornada Mundial de Lucha contra los Transg\u00e9nicos, que se realiz\u00f3 simult\u00e1neamente en 300 ciudades de 40 pa\u00edses del mundo.<\/p>\n<p>Con la participaci\u00f3n de m\u00e1s de 100 organizaciones de productores org\u00e1nicos, de comercio justo, ambientalistas y empresas comprometidas con no usar OGMs, tanto del Distrito Federal como de diversos estados de la rep\u00fablica, se ofrecieron al p\u00fablico una gran diversidad de productos alimenticios frescos y procesados, artesan\u00edas elaboradas con manejo sustentable de los recursos naturales y publicaciones, videos e informaci\u00f3n sobre OGMs, patentes, plaguicidas, agricultura ecol\u00f3gica, derechos de los pueblos ind\u00edgenas, etc. Adem\u00e1s, la Feria se celebr\u00f3 tambi\u00e9n en otras 7 ciudades del pa\u00eds, impulsada por la Red Mexicana de Tianguis Org\u00e1nicos y Mercados Locales.<\/p>\n<p>Esta feria fue posible gracias al apoyo y patrocinio de personas y empresas comprometidas con esta causa como la Diputada Independiente de la Asamblea Legislativa del Distrito Federal, Martha Delgado Peralta; The Green Corner, Astral, Aires de campo, Alejandro Villase\u00f1or de Tecnoman\u00eda y Marco D\u00edaz Le\u00f3n, del Programa &#8220;Del Campo y de la ciudad&#8221;, se encarg\u00f3 de la conducci\u00f3n y animaci\u00f3n del evento durante todo el d\u00eda, y de anuncios semanales en Radio Educaci\u00f3n.<\/p>\n<p>Durante la Feria el Comit\u00e9 organizador de esta iniciativa (Greenpeace, Grupo de Estudios Ambientales GEA, Red Mexicana de Tianguis Org\u00e1nicos y Mercados Locales, The Green Corner, Aires de Campo, ANEC, Comercio Justo M\u00e9xico, Red Ecologista Aut\u00f3noma de la Cuenca de M\u00e9xico Ecomunidades, Oxfam, y Programa de Agricultura Org\u00e1nica del D.F.), presentaron el sello &#8220;Sin OGMs &#8211; Libre de transg\u00e9nicos&#8221; y se present\u00f3 un documento de Diez preguntas sobre agricultura, alimentaci\u00f3n y justicia, dirigido a los candidatos presidenciales.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2119 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/Feria-alimentacion-sin-transgenicos-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"138\" src=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/Feria-alimentacion-sin-transgenicos-1-200x138.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/Feria-alimentacion-sin-transgenicos-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"138\" src=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/Feria-alimentacion-sin-transgenicos-2-200x138.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>8 de abril 2006<\/p>\n","protected":false},"author":1,"featured_media":2120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11,19],"tags":[],"class_list":["post-2119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diputada","category-legislacion-ambiental"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/comments?post=2119"}],"version-history":[{"count":6,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2119\/revisions"}],"predecessor-version":[{"id":5982,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2119\/revisions\/5982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media\/2120"}],"wp:attachment":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media?parent=2119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/categories?post=2119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/tags?post=2119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}