{"id":2073,"date":"2012-04-24T16:57:00","date_gmt":"2012-04-24T16:57:00","guid":{"rendered":"http:\/\/martha.org.mx\/una-politica-con-causa\/?p=2073"},"modified":"2019-07-12T15:57:38","modified_gmt":"2019-07-12T15:57:38","slug":"transporte-publico-eficiente-y-seguro","status":"publish","type":"post","link":"https:\/\/martha.org.mx\/una-politica-con-causa\/transporte-publico-eficiente-y-seguro\/","title":{"rendered":"Transporte p\u00fablico"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright\"><a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/Metro-DF-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"220\" src=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/Metro-DF-2.jpg\" alt=\"\" class=\"wp-image-2082\"\/><\/a><\/figure><\/div>\n\n\n\n<p>Somos millones de ciudadanos los que queremos un transporte digno. Los habitantes del Distrito Federal invertimos mucho tiempo y recursos en movilizarnos, y merecemos un sistema de transporte eficiente, acorde con los horarios laborales y la estructura de la Ciudad, y sobre todo seguro y no contaminante. Las mujeres padecemos de humillaciones y violencia en las horas de alta demanda en el Metro, los peseros y los camiones. Por ello es necesario:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Aumentar el presupuesto de la partida asignada a transporte en la Ciudad, para construir un nuevo sistema de corredores con carriles reservados para el transporte colectivo, sustituir los microbuses por veh\u00edculos de mayor capacidad y que utilicen combustibles alternativos, y crear un sistema integrado de transporte p\u00fablico metropolitano en coordinaci\u00f3n con el Estado de M\u00e9xico.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Asignar flotillas de camiones para uso exclusivo de mujeres y ni\u00f1os en horas de alta afluencia, designar mayor vigilancia a todo el sistema de transporte y tener un control estricto de choferes y paradas.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Fomentar el uso de la bicicleta como medio alternativo de transporte, destinar espacios exclusivos para el uso de la bicicleta quit\u00e1ndole espacio al autom\u00f3vil, fomentando una cultura de respeto hacia los peatones y ciclistas.<\/li><\/ul>\n\n\n\n<p><strong>DIAGN\u00d3STICO<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/taquilla-metro.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/taquilla-metro-300x180.jpg\" alt=\"\" class=\"wp-image-2084\" srcset=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/taquilla-metro-300x180.jpg 300w, https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/taquilla-metro.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>El sistemas de transporte que operan en el Distrito Federal con distribuci\u00f3n modal est\u00e1 formada por la Red de transportes de pasajeros (RTP), Sistema de transporte el\u00e9ctricos, Sistema de Transporte Colectivo &#8211; Metro.<\/p>\n\n\n\n<p>El Sistema de Transporte Colectivo SCT-Metro tiene una red de 200 kil\u00f3metros de v\u00edas dobles -en 11 L\u00edneas y 175 estaciones- los cuales son recorridos diariamente por los 302 trenes que conforman el parque vehicular, de los cuales 201 se tienen programados para la operaci\u00f3n diaria, realizando 1 mill\u00f3n 157 mil 490 vueltas anuales, lo que se traduce en una oferta de servicio de 3.4 millones de lugares anuales.<\/p>\n\n\n\n<p>El sistema capta en promedio 3.8 millones de pasajeros en d\u00eda laborable; en el periodo 1995-1998 la afluencia de usuarios se redujo en cerca de 9%, pero con la entrada en operaci\u00f3n de la L\u00ednea B, de 1998 a 2000 se obtuvo un incremento cercano al 4%. El desarrollo del Sistema se ha dado en la porci\u00f3n centro y norte del Distrito Federal. El d\u00eda 30 de noviembre del 2000, se puso en marcha la segunda etapa de la L\u00ednea \u201cB\u201d, la cual comprende 10.5 km de v\u00edas y 8 estaciones, que van desde la estaci\u00f3n Continentes hasta la terminal Ciudad Azteca, obra que permiti\u00f3 unir al centro de la Ciudad de M\u00e9xico con dos zonas de alta densidad de poblaci\u00f3n en el Estado de M\u00e9xico: Ecatepec y Nezahualc\u00f3yotl, transportado a la fecha aproximadamente a 44 millones de pasajeros).<\/p>\n\n\n\n<p>Servicio de Transportes El\u00e9ctricos (STE), en el cual opera la red de trolebuses y la l\u00ednea del tren ligero. La red actual de trolebuses tiene una extensi\u00f3n de 422.14 Km, con 17 l\u00edneas, y un promedio de 344 unidades en operaci\u00f3n. Por su parte, la l\u00ednea del tren ligero tiene una longitud de 13 kil\u00f3metros a doble v\u00eda y opera en promedio con 12 trenes en horas valle y 15 en horas de m\u00e1xima demanda. Las caracter\u00edsticas b\u00e1sicas de operaci\u00f3n de las l\u00edneas del STE y el total de pasajeros atendidos durante el 2000 se presenta en la tabla de la p\u00e1gina anterior.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/RTP-Metro.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"231\" height=\"300\" src=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/RTP-Metro-231x300.jpg\" alt=\"\" class=\"wp-image-2086\" srcset=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/RTP-Metro-231x300.jpg 231w, https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/RTP-Metro.jpg 583w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>La Red de Transporte de Pasajeros (RTP) cuenta actualmente con un total de 1 mil 409 unidades en condiciones de operaci\u00f3n, de las cuales 726 son de reciente adquisici\u00f3n (el 20 de marzo de 2001 se incorporaron al servicio 200 autobuses nuevos: 120 ligeros y 80 sencillos), el resto de las unidades presentan una antig\u00fcedad promedio de 12 a\u00f1os. En promedio los autobuses recorren diariamente un aproximado de 250 mil kil\u00f3metros.<\/p>\n\n\n\n<p>Transporte concesionado, se encuentran en operaci\u00f3n nueve empresas concesionarias de autobuses, con un parque vehicular total de 1 mil 197 unidades y 97 rutas, con una extensi\u00f3n de m\u00e1s de 3 mil kil\u00f3metros. En estas rutas, de acuerdo con los estudios t\u00e9cnicos previos al otorgamiento de las respectivas concesiones, se estima que pueden transportarse cerca de 1.2 millones de pasajeros por d\u00eda, con una captaci\u00f3n superior a los 900 pasajeros por unidad, en un d\u00eda.<\/p>\n\n\n\n<p>En el a\u00f1o 2000, se registr\u00f3 un total de 27 mil 928 veh\u00edculos con placas para el servicio de ruta fija de los cuales el 82% eran minibuses, 14% vagonetas y el restante 4% autobuses. Tambi\u00e9n se registr\u00f3 un total de 102 mil 110 unidades en el servicio de taxi, de los cuales el 90% correspondieron a taxis libres, y el resto a taxis de sitio, esta cifra representa un incremento de 17% con respecto a los 87 mil 499 taxis registrados en 1997. Se estima que esta flota vehicular atiende diariamente poco m\u00e1s de 1.1 millones de viajes diarios.<\/p>\n\n\n\n<p>En la pr\u00e1ctica el servicio concesionado atiende a m\u00e1s de la mitad de los viajes que se realizan en la ciudad, no obstante que sus condiciones de calidad y seguridad no son las adecuadas. El reparto modal interno del transporte p\u00fablico se ha modificado considerablemente en los \u00faltimos a\u00f1os, los medios de transporte de baja capacidad (taxis, microbuses, combis) han incrementado fuertemente su participaci\u00f3n modal en detrimento del transporte masivo. Adem\u00e1s se a favorecido el uso del autom\u00f3vil particular.<\/p>\n\n\n\n<p>Los sistemas de transporte masivos y colectivos, multimodales contribuyen a establecer ciudades m\u00e1s densas, con diversidad en los usos de suelo y con menores impactos ambientales y territoriales. En contraste los sistemas de transporte que dependen mayoritariamente en el transporte privado favorecen la expansi\u00f3n urbana y una estructura urbana m\u00e1s segregada. El sistema de transporte p\u00fablico que funciona en la Ciudad de M\u00e9xico hoy en d\u00eda es ineficiente, depende mayoritariamente en modos de transportes de baja capacidad que tienen altos impactos urbanos y ambientales y que no garantizan una movilidad r\u00e1pida y eficiente de personas y mercanc\u00edas.<\/p>\n\n\n\n<p><strong>OTRAS PROPUESTAS<br><\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright\"><a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/contaminaci\u00f3n-transporte-p\u00fablico.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2012\/04\/contaminaci\u00f3n-transporte-p\u00fablico.jpg\" alt=\"\" class=\"wp-image-2088\"\/><\/a><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Promover la creaci\u00f3n de una pol\u00edtica integral de transporte sostenible que garantice la movilidad de las personas y mercanc\u00edas en la ZMVM.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Trabajar por la creaci\u00f3n y mejoramiento de modelos de transporte seguros, eficientes y menos contaminantes, los cuales desincentiven el uso del autom\u00f3vil y fomenten el uso del transporte p\u00fablico.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Reducir las emisiones de Gases Efecto Invernadero (GEI) del sector transporte, reducir el uso de combustibles f\u00f3siles, introducir combustibles limpios y aplicar tecnolog\u00edas mejoradas en el parque vehicular de la Ciudad de M\u00e9xico.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Fortalecer y ampliar el transporte p\u00fablico del Gobierno del D.F.: Red de transportes de pasajeros RTP, Sistema de transporte el\u00e9ctricos, Red del metro. Crear un sistema integrado con intersecci\u00f3n modal (tarjeta \u00fanica de pago).<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Sustituci\u00f3n de taxis viejos por unidades nuevas.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Regular la operaci\u00f3n de los microbuses y exigir calidad total en su operaci\u00f3n: ch\u00f3feres con uniforme, horarios fijos, sueldos por kil\u00f3metros recorridos, limpieza y mantenimiento de los microbuses.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Sustituci\u00f3n de microbuses viejos por veh\u00edculos de mayor capacidad, y desarrollar un sistema alternativo para remplazar los microbuses, como el plan de corredores de transporte publico (BRT).<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Fomentar el uso de la bicicleta como medio alternativo de transporte, destinar espacios exclusivos para el uso de la bicicleta quit\u00e1ndole espacio al autom\u00f3vil.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Fomentar una cultura de respeto hacia los peatones y ciclistas, en donde todos podamos circular con seguridad en las calles.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Fortalecer una cultura c\u00edvica en la ciudad orientada al cumplimiento de las leyes y reglamentos de transito.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Promover la participaci\u00f3n ciudadana en temas urbanos.<\/li><\/ul>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Fortalecer el acceso a informaci\u00f3n sobre temas urbanos y ambientales en la Ciudad de M\u00e9xico.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Problemas y propuestas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[90,26,64],"tags":[],"class_list":["post-2073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-escritos-por-martha-delgado","category-transporte-sustentable","category-transporte-sustentable-martha"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/comments?post=2073"}],"version-history":[{"count":16,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2073\/revisions"}],"predecessor-version":[{"id":5213,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/2073\/revisions\/5213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media\/5212"}],"wp:attachment":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media?parent=2073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/categories?post=2073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/tags?post=2073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}