{"id":14324,"date":"2024-07-18T13:34:27","date_gmt":"2024-07-18T13:34:27","guid":{"rendered":"https:\/\/martha.org.mx\/una-politica-con-causa\/?p=14324"},"modified":"2024-07-26T13:55:17","modified_gmt":"2024-07-26T13:55:17","slug":"las-razones-y-el-futuro-de-la-politica-exterior-feminista","status":"publish","type":"post","link":"https:\/\/martha.org.mx\/una-politica-con-causa\/las-razones-y-el-futuro-de-la-politica-exterior-feminista\/","title":{"rendered":"Las razones y el futuro de la pol\u00edtica exterior feminista"},"content":{"rendered":"\n<p>Por Martha Delgado y Cristopher Ballinas publicado en<a href=\"https:\/\/www.cronica.com.mx\/opinion\/razones-futuro-politica-exterior-feminista.html\" title=\"\"> La Cr\u00f3nica de hoy <\/a>el <a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-content\/uploads\/2024\/07\/LaCronica.-MDP-y-CBV-origen-PEF.pdf\" title=\"\">18 de julio de 2024<\/a><\/p>\n\n\n\n<p>Durante la 74 Asamblea General de la ONU en septiembre de 2019, el canciller Marcelo Ebrard anunci\u00f3 que M\u00e9xico adoptar\u00eda una Pol\u00edtica Exterior Feminista (PEF). En ese entonces, no hab\u00eda m\u00e1s de un pu\u00f1ado de pa\u00edses con una pol\u00edtica similar y M\u00e9xico se convirti\u00f3 en el primer pa\u00eds del Sur Global en adoptar una. La PEF mexicana se caracteriz\u00f3 por no s\u00f3lo buscar un impacto a trav\u00e9s de las acciones de cooperaci\u00f3n, sino que prioriz\u00f3 los derechos de las mujeres y las ni\u00f1as en todas las posiciones internacionales del gobierno, y se propici\u00f3 la defensa de los derechos de las mujeres tambi\u00e9n hacia el interior. Apenas cuatro a\u00f1os despu\u00e9s, los resultados de la PEF fueron reconocidos por el Feminist Foreign Policy Index: A Quantitative Evaluation of Feminist Commitments realizado por el Centro Internacional para la Investigaci\u00f3n sobre las Mujeres (ICRW), catalog\u00e1ndola dentro de las tres mejores del mundo, \u00fanicamente detr\u00e1s de las de Suecia y Noruega, y la primera del Sur Global.<\/p>\n\n\n\n<p>Cuando comenzamos con la idea, durante del proceso de transici\u00f3n antes de la entrada al nuevo gobierno, las pol\u00edticas exteriores feministas eran algo nuevo y no cabalmente comprendidas; incluso algunos diplom\u00e1ticos y organizaciones las interpretaban como un \u201cmembrete\u201d o una forma de \u201cpink washing\u201d de los gobiernos. En consultas con expertas, organizaciones, y miembros del Senado coincid\u00edan que M\u00e9xico no s\u00f3lo deber\u00eda adoptar una PEF, sino que podr\u00eda llevarla a un siguiente nivel, aprovechando el inmejorable momento de la entrada de un nuevo gobierno que reivindicaba la lucha de grupos hist\u00f3ricamente discriminados, y la imperante necesidad de mejorar la vida de las mujeres y las ni\u00f1as en M\u00e9xico y en el mundo.<\/p>\n\n\n\n<p>El primer objetivo era pol\u00edtico, en el mejor sentido. Al anunciar una pol\u00edtica exterior feminista en la Asamblea General de la ONU, y posteriormente durante la Reuni\u00f3n anual de personas embajadoras y c\u00f3nsules, se refrendaba el compromiso del Gobierno de M\u00e9xico con la igualdad de g\u00e9nero a nivel internacional, enviando las se\u00f1ales adecuadas a los grupos que t\u00edpicamente se oponen a la defensa de los derechos de las mujeres en los foros multilaterales. El segundo objetivo era conseguir la congruencia y promover espacios para el desarrollo personal y profesional de la SRE, adem\u00e1s de una acci\u00f3n frontal para erradicar la violencia de g\u00e9nero al interior de la Canciller\u00eda, y no s\u00f3lo en el servicio exterior (SEM). <\/p>\n\n\n\n<p>As\u00ed, tras un diagn\u00f3stico de los puntos cr\u00edticos donde las mujeres enfrentan serios retos para ascender en su carrera, se hizo una propuesta de reforma a la Ley del SEM aprobada r\u00e1pidamente en el Senado y que se encuentra en revisi\u00f3n de la C\u00e1mara de Diputadas y Diputados, que de aprobarse ser\u00eda la primera ley en su tipo, que incluye una perspectiva de g\u00e9nero y dota de derechos para un desarrollo profesional igualitario en un lugar donde t\u00edpicamente se interpretaba la norma a favor de los hombres sobre el derecho de las mujeres. El tercer objetivo, es que se honrara la lucha feminista latinoamericana, siendo decolonialista y pensando los derechos de las mujeres desde esta perspectiva, y no unirse autom\u00e1ticamente a las declaraciones y votos del \u201cmainstream\u201d feminista europe\u00edsta, sobre todo en las discusiones internacionales que m\u00e1s impactan a las mujeres del sur global: violencia, cambio clim\u00e1tico, violencia, alimentaci\u00f3n y salud, entre otros temas.<\/p>\n\n\n\n<p>Nos sentimos satisfechos con lo conseguido en estos primeros a\u00f1os de la PEF, y de la gran relevancia que adquiri\u00f3 llamando la atenci\u00f3n de sus pares, de la academia, y de las organizaciones sociales, quienes demandaron conocer m\u00e1s de ella y acompa\u00f1arla para potenciar su efectividad. Esto no s\u00f3lo es un reconocimiento, sino tambi\u00e9n implica la responsabilidad de mantener los m\u00e1s altos est\u00e1ndares en la acci\u00f3n internacional, as\u00ed como para procurar que esta pol\u00edtica exterior tuviera un impacto en la pol\u00edtica interna, y con ello contribuir a erradicar la violencia de g\u00e9nero que tanto afecta a las mujeres y ni\u00f1as en nuestro pa\u00eds y en el mundo.<\/p>\n\n\n\n<p>El pr\u00f3ximo gobierno est\u00e1 obligado no s\u00f3lo a la paridad, sino a trabajar inmediatamente para corregir las cuestiones estructurales que impiden el correcto y igualitario desarrollo de las mujeres y las ni\u00f1as, as\u00ed como otros grupos hist\u00f3ricamente discriminados. En M\u00e9xico prevalece una estructura social desigual que normaliza la opresi\u00f3n y la violencia contra las mujeres. Con una PEF implementada en toda su capacidad, y con un bloque de pa\u00edses latinoamericanos que anunciaron una pol\u00edtica similar; se pueden llevar las visiones feministas latinoamericanas a la discusi\u00f3n global. Se dejaron cimientos fuertes para su continuidad en el largo plazo, por lo que es viable no solo continuar sino diversificar la PEF, amplificando su papel actual en las agendas multilaterales de cooperaci\u00f3n, medio ambiente, salud, derechos ind\u00edgenas, de desarrollo, finanzas, e incluso del arte y la cultura, lo que podr\u00eda contribuir a la construcci\u00f3n de un M\u00e9xico cada vez m\u00e1s justo, incluyente y seguro para las mujeres y las ni\u00f1as, y al prop\u00f3sito global de crear sociedades justas y equitativas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Martha Delgado y Cristopher Ballinas publicado en La Cr\u00f3nica de hoy el 18 de julio de 2024 Durante la 74 Asamblea General de la ONU en septiembre de 2019, el canciller Marcelo Ebrard anunci\u00f3 que M\u00e9xico adoptar\u00eda una Pol\u00edtica Exterior Feminista (PEF). En ese entonces, no hab\u00eda m\u00e1s de un pu\u00f1ado de pa\u00edses con&hellip;<\/p>\n<p class=\"more-link\"><a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/las-razones-y-el-futuro-de-la-politica-exterior-feminista\/\" class=\"themebutton\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[90],"tags":[],"class_list":["post-14324","post","type-post","status-publish","format-standard","hentry","category-articulos-escritos-por-martha-delgado"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/14324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/comments?post=14324"}],"version-history":[{"count":1,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/14324\/revisions"}],"predecessor-version":[{"id":14326,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/14324\/revisions\/14326"}],"wp:attachment":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media?parent=14324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/categories?post=14324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/tags?post=14324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}