{"id":1166,"date":"2012-02-04T00:42:52","date_gmt":"2012-02-04T00:42:52","guid":{"rendered":"http:\/\/yogaparatodos-en-mexico.com\/martha\/?p=1166"},"modified":"2019-08-14T17:30:00","modified_gmt":"2019-08-14T17:30:00","slug":"lineas-discursivas-para-el-proaire-2011-2020","status":"publish","type":"post","link":"https:\/\/martha.org.mx\/una-politica-con-causa\/lineas-discursivas-para-el-proaire-2011-2020\/","title":{"rendered":"L\u00edneas discursivas para el PROAIRE 2011-2020"},"content":{"rendered":"<p>15 de diciembre del 2011<br \/>\n\u2022 Han transcurrido casi diez a\u00f1os del desarrollo, implementaci\u00f3n, y seguimiento del PROAIRE de la Zona Metropolitana del Valle de M\u00e9xico 2002-2010, donde la administraci\u00f3n del Gobierno del Distrito Federal, la Secretar\u00eda del Medio Ambiente del Gobierno del Estado de M\u00e9xico y la Secretar\u00eda del Medio Ambiente y Recursos Naturales (SEMARNAT) bajo la coordinaci\u00f3n de la Comisi\u00f3n Ambiental Metropolitana (CAM), junto con la ciudadan\u00eda, unieron esfuerzos, en el desarrollo de los trabajos para mejorar la calidad del aire de esta megal\u00f3polis.<br \/>\n\u2022 Con el mismo objetivo de seguir mejorando la calidad del aire de esta metr\u00f3poli, las autoridades ambientales que constituyen la CAM, han integrado un nuevo documento denominado \u201cPrograma para mejorar la calidad del aire de la Zona Metropolitana del Valle de M\u00e9xico 2011-2020\u201d, que pretende ser un instrumento din\u00e1mico en el conjunto de pol\u00edticas p\u00fablicas que se implementar\u00e1n en la Zona Metropolitana del Valle de M\u00e9xico (ZMVM), las cuales pretenden tener resultados evidentes que contin\u00faen disminuyendo las emisiones y concentraciones de los contaminantes criterio, t\u00f3xicos y de efecto invernadero durante la presente d\u00e9cada.<br \/>\n\u2022 Las pol\u00edticas para mejorar la calidad del aire implementadas en los \u00faltimos 20 a\u00f1os han permitido reducir los niveles de algunos de los contaminantes criterio y mantenerlos en niveles por debajo de sus normas de protecci\u00f3n de la salud, sin embargo, aunque se han logrado incrementar los d\u00edas dentro de norma para el ozono y las part\u00edculas suspendidas, estos dos contaminantes criterio a\u00fan siguen presentando excedencias a la norma de protecci\u00f3n a la salud.<br \/>\n\u2022 La tendencia de los niveles de part\u00edculas menores a 10 micr\u00f3metros, indica una disminuci\u00f3n progresiva de 1990 a 2010 de 53% y para el ozono la reducci\u00f3n de las concentraciones ha sido continua desde 1992, presentando hasta el a\u00f1o 2010 respecto a 1990 una disminuci\u00f3n del 46%.<br \/>\n\u2022 Los inventarios de las emisiones estimadas para el 2008 en la ZMVM indican que las fuentes contaminantes en su conjunto emiten aproximadamente 2.7 millones de toneladas por a\u00f1o, de las cuales el 70% es generado por los veh\u00edculos automotores, el 23% por las actividades comerciales, de servicio y los hogares, el 6% por las grandes industrias y termoel\u00e9ctricas y el 1% por la vegetaci\u00f3n y los suelos.<br \/>\n\u2022 Por lo que se refiere a los compuestos t\u00f3xicos, se emiten anualmente a la atm\u00f3sfera poco m\u00e1s de 183 mil toneladas siendo los autos particulares (13%), junto con la limpieza y el recubrimiento de superficies industriales (21%) los principales emisores; y de los gases de efecto invernadero se emiten 51.5 millones de toneladas equivalentes de di\u00f3xido de carbono, y los autos particulares (23%) y los rellenos sanitarios (15%) son los principales emisores.<br \/>\n\u2022 La Secretar\u00eda del Medio Ambiente del Gobierno del Distrito Federal, contrat\u00f3 al Instituto Nacional de Salud P\u00fablica para realizar el estudio \u201cEstado del conocimiento sobre los efectos en la salud asociados a la contaminaci\u00f3n del aire de la poblaci\u00f3n de la Zona Metropolitana de la Ciudad de M\u00e9xico\u201d, los resultados obtenidos indican que si se cumpliera cabalmente con la norma actual mexicana de PM10, en mantener el promedio anual en 50 \u00b5g\/m3, se evitar\u00edan 400 muertes prematuras en el corto plazo; asimismo, se ha encontrado evidencia que asocia al ozono con un incremento en las tasas de mortalidad, por lo que una reducci\u00f3n en la concentraci\u00f3n promedio de ozono de 50 ppb evitar\u00eda cerca de 400 muertes prematuras en la ZMVM.<br \/>\n\u2022 La SMA del Distrito Federal con recursos autorizados del Fideicomiso 1490, instal\u00f3 la red de monitoreo de COV, que son los compuestos que de acuerdo con los \u00faltimos estudios cient\u00edficos realizados en la ZMVM, contribuyen en la formaci\u00f3n de ozono y part\u00edculas finas secundarias y adem\u00e1s dentro de ellos se encuentran los compuestos t\u00f3xicos que causan serios da\u00f1os en la salud de la poblaci\u00f3n.<br \/>\n\u2022 En el a\u00f1o de 2003 se instal\u00f3 la red de monitoreo para part\u00edculas PM2.5 la cual ha generado suficiente informaci\u00f3n que se tom\u00f3 en cuenta para determinar las pol\u00edticas que se aplicar\u00e1n en los pr\u00f3ximos a\u00f1os para reducir las emisiones de este contaminante.<br \/>\n\u2022 Para el desarrollo de este nuevo programa, se cont\u00f3 con una amplia informaci\u00f3n y nuevos hallazgos cient\u00edficos, por ejemplo, entre las aportaciones del Dr. Mario Molina y sus estudios realizados en el a\u00f1o 2003 y el 2006, se puede decir que en la actualidad la fotoqu\u00edmica de la atm\u00f3sfera de la ZMVM es altamente reactiva y que ahora la formaci\u00f3n del ozono depende de los Compuestos Org\u00e1nicos Vol\u00e1tiles (COV) que se generan en las primeras horas de la ma\u00f1ana.<br \/>\n\u2022 Se realizaron dos talleres internacionales para conocer que se est\u00e1 haciendo en otros pa\u00edses en materia de calidad del aire y recibir las recomendaciones de expertos de alto nivel. Adem\u00e1s se realiz\u00f3 una reuni\u00f3n con investigadores nacionales que participaron en el proyecto MILAGRO, para recibir las recomendaciones sobre las pol\u00edticas p\u00fablicas que se aplicar\u00e1n en los pr\u00f3ximos a\u00f1os.<br \/>\n\u2022 El PROAIRE 2011-2020 tiene una nueva visi\u00f3n, que toma en cuenta el desarrollo urbano, la congesti\u00f3n vehicular, la emisi\u00f3n de contaminantes criterio, t\u00f3xicos y de efecto invernadero, con ello se dise\u00f1\u00f3 un an\u00e1lisis ecosist\u00e9mico que permite visualizar la contaminaci\u00f3n atmosf\u00e9rica no s\u00f3lo como un problema aislado dependiente de las fuentes que generan la contaminaci\u00f3n, sino como el resultado de la complejidad de factores que intervienen en forma indirecta como lo aspectos culturales, el crecimiento urbano, la falta de un sistema integral de transporte en toda la zona, el n\u00famero de viajes y la necesidad de los mismos, entre otros.<br \/>\n\u2022 En el nuevo PROAIRE se tom\u00f3 como base el crecimiento de la mancha urbana y el desarrollo urbano, realizando un an\u00e1lisis ecosist\u00e9mico desarrollado para presentar nuevas alternativas en el mejoramiento de la calidad del aire. Este nuevo programa analiza la relaci\u00f3n end\u00f3gena entre la estructura urbana y el sistema de generaci\u00f3n de contaminantes y coloca el tema de la protecci\u00f3n a la salud como punto estrat\u00e9gico y prioritario para mejorar la calidad del aire en el Valle de M\u00e9xico.<br \/>\n\u2022 Este PROAIRE agrupa en 8 estrategias 81 medidas con 116 acciones que deber\u00e1n ser aplicadas en los pr\u00f3ximos 10 a\u00f1os en la Zona Metropolitana del Valle de M\u00e9xico.<br \/>\n\u2022 Con la aplicaci\u00f3n de las medidas propuestas en este nuevo PROAIRE 2011-2020 se estima obtener una reducci\u00f3n en las emisiones de contaminantes criterio en m\u00e1s de 490 mil toneladas, una reducci\u00f3n de m\u00e1s de 5 mil toneladas de contaminantes t\u00f3xicos y una reducci\u00f3n de m\u00e1s de 5 millones 500 mil toneladas de gases de efecto invernadero.<br \/>\n\u2022 El costo de implementaci\u00f3n de las medidas del nuevo PROAIRE 2011-2020 se estim\u00f3 en m\u00e1s de 54,390 millones de pesos, de estos 27,765 millones provendr\u00e1n de los Gobiernos del Distrito Federal, del Estado de M\u00e9xico y del Gobierno federal y 26,625 de inversi\u00f3n privada.<br \/>\n\u2022 El Gobierno del Distrito Federal ha iniciado algunas acciones contempladas en este programa como es el uso de la bicicleta como modo de transporte y la ampliaci\u00f3n del METROBUS con la introducci\u00f3n de nuevas rutas de corredores de trasporte de pasajeros donde se han incorporado autobuses nuevos en sustituci\u00f3n de microbuses.<br \/>\n\u2022 Los grandes retos de este programa se pueden resumir en los siguientes: poder tener un sistema de transporte metropolitano, suministro de combustibles de ultrabajo contenido de azufre todo el pa\u00eds para que con ello los fabricantes de veh\u00edculos puedan comercializar unidades con tecnolog\u00edas de control de emisiones limpias, reducir el n\u00famero y distancias de los viajes realizados en la ZMVM, cambiar los usos de medios de transporte de individual a masivo e ir incrementando el n\u00famero de personas que usen el transporte no motorizado, actualizar y complementar el marco normativo para abatir las emisiones de compuestos org\u00e1nicos vol\u00e1tiles, propiciar los cambios educativos y culturales, as\u00ed como la participaci\u00f3n social que ayuden a mejorar la eficiencia del ecosistema metropolitano entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>15 de diciembre del 2011 \u2022 Han transcurrido casi diez a\u00f1os del desarrollo, implementaci\u00f3n, y seguimiento del PROAIRE de la Zona Metropolitana del Valle de M\u00e9xico 2002-2010, donde la administraci\u00f3n del Gobierno del Distrito Federal, la Secretar\u00eda del Medio Ambiente del Gobierno del Estado de M\u00e9xico y la Secretar\u00eda del Medio Ambiente y Recursos Naturales&hellip;<\/p>\n<p class=\"more-link\"><a href=\"https:\/\/martha.org.mx\/una-politica-con-causa\/lineas-discursivas-para-el-proaire-2011-2020\/\" class=\"themebutton\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":3827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13,25],"tags":[],"class_list":["post-1166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial","category-secretaria"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/1166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/comments?post=1166"}],"version-history":[{"count":2,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/1166\/revisions"}],"predecessor-version":[{"id":6030,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/posts\/1166\/revisions\/6030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media\/3827"}],"wp:attachment":[{"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/media?parent=1166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/categories?post=1166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/martha.org.mx\/una-politica-con-causa\/wp-json\/wp\/v2\/tags?post=1166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}